{"id":47188,"date":"2026-02-20T04:00:50","date_gmt":"2026-02-20T03:00:50","guid":{"rendered":"https:\/\/neocatechumenaleiter.org\/kiko-arguello-e-la-sua-opera-sinfonica-nella-cattedrale-di-toledo\/"},"modified":"2026-03-20T22:49:51","modified_gmt":"2026-03-20T21:49:51","slug":"kiko-arguello-e-la-sua-opera-sinfonica-nella-cattedrale-di-toledo","status":"publish","type":"post","link":"https:\/\/neocatechumenaleiter.org\/it\/kiko-arguello-e-la-sua-opera-sinfonica-nella-cattedrale-di-toledo\/","title":{"rendered":"Kiko Arg\u00fcello e la sua Opera Sinfonica nella Cattedrale di Toledo"},"content":{"rendered":"\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\">\n<p>In occasione dell&#8217;800\u00b0 anniversario della posa della prima pietra dell&#8217;attuale cattedrale gotica di Toledo, in Spagna, il pittore e compositore spagnolo Kiko Arg\u00fcello presenter\u00e0 domenica 22 febbraio 2026 la sua Opera Sinfonica composta dai brani: \u201cEl Sufrimiento de los Inocentes\u201d (La sofferenza degli innocenti) e \u201cEl Mes\u00edas\u201d (Il Messia).<\/p>\n<\/blockquote>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.youtube.com\/watch?v=3uRTWSYx3Q0\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"614\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-1024x614.jpg\" alt=\"\" class=\"wp-image-47133\" srcset=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-1024x614.jpg 1024w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-300x180.jpg 300w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-768x461.jpg 768w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-1536x922.jpg 1536w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><\/figure><\/div>\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"245\" height=\"92\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-arquidiocesis-todelo-logo.jpg\" alt=\"\" class=\"wp-image-47157\"\/><\/figure><\/div>\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h4 class=\"wp-block-heading has-text-align-center\">Comunicato stampa dell&#8217;Arcidiocesi di Toledo<\/h4>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>In occasione dell&#8217;ottavo centenario della posa della prima pietra dell&#8217;attuale cattedrale gotica, Kiko Arg\u00fcello presenter\u00e0 l&#8217;opera in un concerto domenica, 22 febbraio, alle 19:30. L&#8217;ingresso sar\u00e0 libero dalla Puerta Llana fino a esaurimento posti.<\/p>\n\n<p>Al concerto sar\u00e0 presente l&#8217;arcivescovo di Toledo, Mons. Francisco Cerro Chaves. Sar\u00e0 diretto dal maestro Tom\u00e1\u0161 Hanus, riconosciuto a livello internazionale, che si \u00e8 esibito in teatri come la Bayerische Staatsoper, l&#8217;Op\u00e9ra di Parigi, il Teatro Real di Madrid e la Scala di Milano. Il pianista Claudio Carb\u00f3 e il direttore del coro Abraham S\u00e1nchez completano il cast artistico.<\/p>\n\n<p>L&#8217;interpretazione sar\u00e0 a cura dell&#8217;Orchestra Sinfonica e del Coro del Cammino Neocatecumenale, fondato nel 2010 e composto da circa 180 musicisti di diverse nazionalit\u00e0 che offrono gratuitamente il loro talento al servizio dell&#8217;evangelizzazione attraverso la musica.<\/p>\n\n<p>Con l&#8217;Opera Sinfonica, Kiko Arg\u00fcello propone un&#8217;esperienza artistica di grande profondit\u00e0 spirituale e forza estetica, dove musica, fede e bellezza si uniscono per offrire all&#8217;uomo contemporaneo una meditazione sonora sul mistero di Cristo e sulla speranza della Resurrezione.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading has-text-align-center\">Il concerto sar\u00e0 trasmesso dalla Televisione Diocesana di Toledo<\/h5>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity is-style-wide\"\/>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div align=\"center\"><iframe loading=\"lazy\" width=\"560\" height=\"315\" src=\"https:\/\/www.youtube.com\/embed\/3uRTWSYx3Q0?si=5NrYbOyTLFxm4_xG\" title=\"YouTube video player\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen=\"\"><\/iframe><\/div>\r\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-gallery aligncenter has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0439cda08f7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0439cda08f7\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"47391\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-06-1-711x1024.jpg\" alt=\"\" class=\"wp-image-47391\" srcset=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-06-1-711x1024.jpg 711w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-06-1-208x300.jpg 208w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-06-1-768x1107.jpg 768w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-06-1-1066x1536.jpg 1066w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-06-1.jpg 1200w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0439cda1067&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0439cda1067\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"711\" height=\"1024\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"47424\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-07-1-711x1024.jpg\" alt=\"\" class=\"wp-image-47424\" srcset=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-07-1-711x1024.jpg 711w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-07-1-208x300.jpg 208w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-07-1-768x1107.jpg 768w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-07-1-1066x1536.jpg 1066w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-07-1.jpg 1200w\" sizes=\"auto, (max-width: 711px) 100vw, 711px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<hr class=\"wp-block-separator aligncenter has-alpha-channel-opacity is-style-wide\"\/>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading\">Intensa attivit\u00e0 artistica<\/h5>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Kiko Arg\u00fcello, iniziatore del Cammino Neocatecumenale, insieme a Carmen Hern\u00e1ndez, Serva di Dio, formatosi all&#8217;Accademia di Belle Arti San Fernando di Madrid e insignito nel 1959 del Premio Nazionale Straordinario di Pittura, ha sviluppato un&#8217;intensa attivit\u00e0 artistica nel campo della pittura, dell&#8217;architettura, della scultura e della musica sacra. La sua opera \u00e8 profondamente legata all&#8217;annuncio del Vangelo attraverso la bellezza, concepita come riflesso della luce di Dio e come strumento per la nuova evangelizzazione.<\/p>\n\n<p>Nel 1964, dopo una profonda esperienza di conversione, decide di vivere tra i poveri nella periferia di Madrid, dove nasce la prima comunit\u00e0 del Cammino Neocatecumenale. Il Cammino \u00e8 oggi presente in 138 nazioni ed \u00e8 stato riconosciuto dalla Santa Sede come un dono dello Spirito Santo per la Chiesa.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading\">L&#8217;arte al servizio della fede<\/h5>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Arg\u00fcello \u00e8 autore di importanti interventi artistici e architettonici in templi e centri ecclesiali in tutto il mondo. La sua concezione dell&#8217;arte come cammino verso Dio gli \u00e8 valsa il riconoscimento internazionale.<\/p>\n\n<p>Il 1\u00b0 dicembre 2024 \u00e8 stato insignito del prestigioso premio \u201cPer Artem ad Deum\u201d, assegnato dall&#8217;associazione polacca SacroExpo sotto il patrocinio del Dicastero per la Cultura e l&#8217;Educazione, in riconoscimento del suo contributo alla fede attraverso l&#8217;arte.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading\">Una proposta musicale di dimensione spirituale e universale<\/h5>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Nel 2010 Kiko Arg\u00fcello compone la sua prima sinfonia, <em>El Sufrimiento de los Inocentes<\/em> (La sofferenza degli innocenti), un&#8217;opera in cinque movimenti che costituisce una profonda meditazione sul mistero della morte di Cristo e sul dolore della Vergine Maria.<\/p>\n\n<p>Successivamente completa <em>\u201cEl Mesias\u201d<\/em> (Il Messia), poema sinfonico per pianoforte, coro e orchestra, strutturato in tre movimenti &#8211; Aquedah, Figlie di Gerusalemme e Il Messia, Leone per vincere &#8211; che formano un trittico incentrato sulla passione e la sofferenza di Cristo, dedicato ai martiri cristiani.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading\">Prime e concerti internazionali<\/h5>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0439cda205f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0439cda205f\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"717\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-04-1024x717.jpg\" alt=\"\" class=\"wp-image-47142\" srcset=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-04-1024x717.jpg 1024w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-04-300x210.jpg 300w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-04-768x538.jpg 768w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-04-1536x1075.jpg 1536w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-04.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div>\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p><em>Il Messia<\/em> \u00e8 stato presentato in anteprima il 19 novembre 2023 al Teatro Verdi di Trieste, con trasmissione su RAI5.<\/p>\n\n<p>Nell&#8217;Anno Giubilare 2025, l&#8217;opera sinfonica \u00e8 stata presentata all&#8217;Auditorium \u201cParco della Musica\u201d di Roma, in occasione del Giubileo delle Famiglie, con l&#8217;esecuzione per la prima volta in una sola serata di entrambe le composizioni. Il concerto \u00e8 stato trasmesso a livello internazionale da RAI5.<\/p>\n\n<p>Nel corso del 2025, l&#8217;opera \u00e8 giunta anche in luoghi simbolici della Spagna, come la Moschea-Cattedrale di Cordova, in occasione del Giubileo di San Pelagio, e l&#8217;Auditorium Pr\u00edncipe Felipe di Oviedo, in occasione del 50\u00b0 anniversario del Cammino Neocatecumenale.<\/p>\n\n<p>Questi concerti si aggiungono a una vasta carriera internazionale che ha portato l&#8217;Orchestra su palcoscenici come il Vaticano, Gerusalemme, Parigi, Berlino, Budapest, Giappone, Stati Uniti e Polonia, tra gli altri.<\/p>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h5 class=\"wp-block-heading\">Anno storico per la Chiesa di Toledo e la cultura<\/h5>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>Nel 2026 Toledo celebra gli 800 anni dall&#8217;inizio della costruzione della sua Cattedrale medievale, promossa dal re Ferdinando III, il Santo, e dall&#8217;Arcivescovo Jim\u00e9nez de Rada, e progettata dal maestro francese Mart\u00edn.<\/p>\n\n<p>Un ampio programma di eventi liturgici, culturali, artistici e patrimoniali si svolgeranno per tutto il 2026 e parte del 2027, in coincidenza con l&#8217;Anno Giubilare concesso dalla Santa Sede.<\/p>\n\n<p>Uno dei grandi appuntamenti culturali sar\u00e0 la mostra \u201cPrimada &#8211; VIII Centenario della Cattedrale di Toledo\u201d, che si inaugurer\u00e0 il 25 maggio e rester\u00e0 aperta fino al 14 ottobre 2026. La mostra riunir\u00e0 oltre 350 capolavori &#8211; dipinti, sculture, codici e arazzi &#8211; che ripercorrono otto secoli di arte, fede e patrimonio, con opere di artisti come El Greco, Vel\u00e1zquez e Zurbar\u00e1n.<\/p>\n\n<p>Oltre a questa mostra, il programma include preludi musicali e concerti nella stessa Cattedrale, come questo dell&#8217;opera sinfonica di Kiko Arg\u00fcello.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0439cda2ad1&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0439cda2ad1\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"744\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-01-1024x744.jpg\" alt=\"\" class=\"wp-image-47140\" srcset=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-01-1024x744.jpg 1024w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-01-300x218.jpg 300w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-01-768x558.jpg 768w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-01-1536x1116.jpg 1536w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-01.jpg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div>\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a0439cda32bb&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a0439cda32bb\" class=\"aligncenter size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-05-1-1024x683.jpg\" alt=\"\" class=\"wp-image-47389\" srcset=\"https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-05-1-1024x683.jpg 1024w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-05-1-300x200.jpg 300w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-05-1-768x512.jpg 768w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-05-1-1536x1024.jpg 1536w, https:\/\/neocatechumenaleiter.org\/wp-content\/uploads\/2026\/02\/camino-neocatecumenal-concierto-obra-sinfonica-catedral-toledo-espana-05-1.jpg 1800w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\taria-label=\"Ingrandisci\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.imageButtonRight\"\n\t\t\tdata-wp-style--top=\"state.imageButtonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure><\/div>\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n","protected":false},"excerpt":{"rendered":"<p>In occasione dell&#8217;800\u00b0 anniversario della posa della prima pietra dell&#8217;attuale cattedrale gotica di Toledo, in Spagna, il pittore e compositore spagnolo Kiko Arg\u00fcello presenter\u00e0 domenica 22 febbraio 2026 la sua Opera Sinfonica composta dai brani: \u201cEl Sufrimiento de los Inocentes\u201d (La sofferenza degli innocenti) e \u201cEl Mes\u00edas\u201d (Il Messia). Comunicato stampa dell&#8217;Arcidiocesi di Toledo In occasione dell&#8217;ottavo centenario della posa della prima pietra dell&#8217;attuale cattedrale gotica, Kiko Arg\u00fcello presenter\u00e0 l&#8217;opera<\/p>\n<div class=\"read-more\"><a class=\"btn read-more-btn\" href=\"https:\/\/neocatechumenaleiter.org\/it\/kiko-arguello-e-la-sua-opera-sinfonica-nella-cattedrale-di-toledo\/\">Leggi tutto<\/a><\/div>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[372,282,371,1258,1695],"tags":[],"class_list":["post-47188","post","type-post","status-publish","format-standard","hentry","category-celebrazione-sinfonica","category-comunicazioni","category-concerti","category-notizie","category-video"],"_links":{"self":[{"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/posts\/47188","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/comments?post=47188"}],"version-history":[{"count":9,"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/posts\/47188\/revisions"}],"predecessor-version":[{"id":48341,"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/posts\/47188\/revisions\/48341"}],"wp:attachment":[{"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/media?parent=47188"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/categories?post=47188"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/neocatechumenaleiter.org\/it\/wp-json\/wp\/v2\/tags?post=47188"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}